{"id":2890,"date":"2024-03-03T18:28:32","date_gmt":"2024-03-03T21:28:32","guid":{"rendered":"https:\/\/ottogaleria.com\/sitio\/teresa-magrane-por-las-ramas\/"},"modified":"2024-05-24T09:39:55","modified_gmt":"2024-05-24T12:39:55","slug":"teresa-magrane-por-las-ramas-en","status":"publish","type":"post","link":"https:\/\/ottogaleria.com\/en\/teresa-magrane-por-las-ramas-en\/","title":{"rendered":"Teresa Magrane, &#8230;por las ramas"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-d44be3e\" data-block-id=\"d44be3e\"><style>.stk-d44be3e{margin-top:40px !important}.stk-d44be3e-column{--stk-columns-spacing:0px !important;--stk-column-gap:40px !important}@media screen and (max-width:689px){.stk-d44be3e{margin-top:30px !important}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-d44be3e-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-e291ef8\" data-v=\"4\" data-block-id=\"e291ef8\"><style>@media screen and (min-width:690px){.stk-e291ef8{flex:var(--stk-flex-grow,1) 1 calc(25% - var(--stk-column-gap,0px) * 1 \/ 2 ) !important}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-e291ef8-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-e291ef8-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-35e3640\" id=\"teresa-magrane\" data-block-id=\"35e3640\"><style>.stk-35e3640{margin-bottom:2px !important}.stk-35e3640 .stk-block-heading__text{color:var(--theme-palette-color-4,#000000) !important}<\/style><h4 class=\"stk-block-heading__text has-text-color has-text-align-center-mobile\">Teresa Magrane<\/h4><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-83634a1\" id=\"por-las-ramas\" data-block-id=\"83634a1\"><style>.stk-83634a1{margin-bottom:16px !important}<\/style><h5 class=\"stk-block-heading__text has-text-align-center-mobile\">&#8230;por las ramas<\/h5><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-25ed19c\" id=\"march-13-to-april-30-2024-br-curator-daniela-arroyo\" data-block-id=\"25ed19c\"><style>.stk-25ed19c{margin-bottom:25px !important}<\/style><h6 class=\"stk-block-heading__text has-text-align-center-mobile\">March 13 to April 30, 2024<br>Curator: Daniela Arroyo<\/h6><\/div>\n\n\n\n<div class=\"wp-block-stackable-button-group stk-block-button-group stk-block stk-9a12ffc\" data-block-id=\"9a12ffc\"><div class=\"stk-row stk-inner-blocks has-text-align-left has-text-align-center-mobile stk-block-content stk-button-group\">\n<div class=\"wp-block-stackable-icon-button stk-block-icon-button stk-block stk-cf0347f\" data-block-id=\"cf0347f\"><style>.stk-cf0347f .stk-button{padding-top:5px !important;padding-right:5px !important;padding-bottom:5px !important;padding-left:5px !important;background:var(--theme-palette-color-8,#ffffff) !important}.stk-cf0347f .stk-button .stk--inner-svg svg:last-child{height:20px !important;width:20px !important}.stk-cf0347f .stk-button .stk--inner-svg svg:last-child,.stk-cf0347f .stk-button .stk--inner-svg svg:last-child :is(g,path,rect,polygon,ellipse){fill:var(--theme-palette-color-4,#000000) !important}<\/style><a class=\"stk-link stk-button stk--hover-effect-darken\" href=\"https:\/\/www.artsy.net\/show\/otto-galeria-dot-dot-dot-por-las-ramas?sort=partner_show_position\" title=\"Ver obras\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M256 512A256 256 0 1 0 256 0a256 256 0 1 0 0 512zM216 336h24V272H216c-13.3 0-24-10.7-24-24s10.7-24 24-24h48c13.3 0 24 10.7 24 24v88h8c13.3 0 24 10.7 24 24s-10.7 24-24 24H216c-13.3 0-24-10.7-24-24s10.7-24 24-24zm40-208a32 32 0 1 1 0 64 32 32 0 1 1 0-64z\"><\/path><\/svg><\/div><\/span><\/a><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon-button stk-block-icon-button stk-block stk-1d3452a\" data-block-id=\"1d3452a\"><style>.stk-1d3452a .stk-button{padding-top:5px !important;padding-right:5px !important;padding-bottom:5px !important;padding-left:5px !important;background:var(--theme-palette-color-8,#ffffff) !important}.stk-1d3452a .stk-button .stk--inner-svg svg:last-child{height:18px !important;width:18px !important}.stk-1d3452a .stk-button .stk--inner-svg svg:last-child,.stk-1d3452a .stk-button .stk--inner-svg svg:last-child :is(g,path,rect,polygon,ellipse){fill:var(--theme-palette-color-8,#ffffff) !important}<\/style><a class=\"stk-link stk-button stk--hover-effect-darken\" href=\"https:\/\/ottogaleria.com\/sitio\/prensa\/\" title=\"Prensa\"><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M168 80c-13.3 0-24 10.7-24 24V408c0 8.4-1.4 16.5-4.1 24H440c13.3 0 24-10.7 24-24V104c0-13.3-10.7-24-24-24H168zM72 480c-39.8 0-72-32.2-72-72V112C0 98.7 10.7 88 24 88s24 10.7 24 24V408c0 13.3 10.7 24 24 24s24-10.7 24-24V104c0-39.8 32.2-72 72-72H440c39.8 0 72 32.2 72 72V408c0 39.8-32.2 72-72 72H72zM176 136c0-13.3 10.7-24 24-24h96c13.3 0 24 10.7 24 24v80c0 13.3-10.7 24-24 24H200c-13.3 0-24-10.7-24-24V136zm200-24h32c13.3 0 24 10.7 24 24s-10.7 24-24 24H376c-13.3 0-24-10.7-24-24s10.7-24 24-24zm0 80h32c13.3 0 24 10.7 24 24s-10.7 24-24 24H376c-13.3 0-24-10.7-24-24s10.7-24 24-24zM200 272H408c13.3 0 24 10.7 24 24s-10.7 24-24 24H200c-13.3 0-24-10.7-24-24s10.7-24 24-24zm0 80H408c13.3 0 24 10.7 24 24s-10.7 24-24 24H200c-13.3 0-24-10.7-24-24s10.7-24 24-24z\"><\/path><\/svg><\/div><\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-af57d4b\" data-v=\"4\" data-block-id=\"af57d4b\"><style>.stk-af57d4b-container{margin-top:12px !important;margin-right:12px !important;margin-bottom:12px !important;margin-left:12px !important}@media screen and (min-width:690px){.stk-af57d4b{flex:var(--stk-flex-grow,1) 1 calc(75% - var(--stk-column-gap,0px) * 1 \/ 2 ) !important}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-af57d4b-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-af57d4b-inner-blocks\">\n<div class=\"wp-block-essential-blocks-accordion\"><div class=\"eb-parent-wrapper eb-parent-eb-accordion-xc024 \"><div class=\"eb-accordion-container eb-accordion-xc024\" data-accordion-type=\"accordion\" data-tab-icon=\"fas fa-angle-right\" data-expanded-icon=\"fas fa-angle-down\" data-transition-duration=\"500\"><div class=\"eb-accordion-inner\">\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-gbbxo eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-xc024\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-xc024\"><span class=\"fas fa-angle-right eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-xc024\"><h5 class=\"eb-accordion-title\">Curatorial text<\/h5><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-xc024\"><div class=\"eb-accordion-content\">\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-e262edb\" data-block-id=\"e262edb\"><p class=\"stk-block-text__text\">An attentive gaze floats in space and is lost in the light that covers everything. A pair of scurry feet in the grass make paths through the crunching sound of remains of leaves, little flowers and branches. Two hands tirelessly imagine how to rescue something new from what is about to be lost.<\/p><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-0a85099\" data-block-id=\"0a85099\"><p class=\"stk-block-text__text\">The most interesting thing about endlessly repeating an action is that by always doing the same thing, new things can always emerge. In this sense, repetition could be thought of as a form of research in itself, as it is the opportunity to explore all the possibilities with which that action can surprise us each time.<\/p><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-76d1245\" data-block-id=\"76d1245\"><p class=\"stk-block-text__text\">Teresa Magrane knew how to find her own method of artistic work, which she reproduces in a sustained way over time and which, each time, gives her a new result. Her inexhaustible process is based on a constant dialogue between her hands, materiality, the environment outside and the machine inside the workshop. She proposes, and everything responds.<\/p><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-dc476b4\" data-block-id=\"dc476b4\"><p class=\"stk-block-text__text\">Her hybrid work between different graphic art techniques often plays with being a painting, a drawing, an engraving\u2026 all of them at the same time. It can be disorienting, just like the atmospheres that her images propose. They could well be a cut out of the ground or a new horizon, depending on who looks at it; because easily recognizable elements become unknown in the plastic game that the artist directs.<\/p><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-0bc0d2a\" data-block-id=\"0bc0d2a\"><p class=\"stk-block-text__text\">That plausible work that Teresa produces among leaves and little flowers, color palettes, lights and shadows, diverse planes and scales, emerge in the gallery space like different thresholds. Arranged there subtly, to look around these new spaces and get lost among the branches.<\/p><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-fca21dd\" data-block-id=\"fca21dd\"><p class=\"stk-block-text__text\"><strong>Daniela Arroyo<\/strong><br>Marzo, 2024<\/p><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-slider\"><div class=\"eb-parent-wrapper eb-parent-eb-slider-bt3bd \"><div class=\"eb-slider-wrapper eb-slider-bt3bd\" data-settings=\"{&quot;arrows&quot;:true,&quot;adaptiveHeight&quot;:false,&quot;autoplay&quot;:true,&quot;autoplaySpeed&quot;:3000,&quot;dots&quot;:false,&quot;fade&quot;:false,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:true,&quot;slidesToShow&quot;:1,&quot;speed&quot;:500,&quot;vertical&quot;:false,&quot;currentSlide&quot;:0,&quot;rtl&quot;:false,&quot;responsive&quot;:[{&quot;breakpoint&quot;:1025,&quot;settings&quot;:{&quot;slidesToShow&quot;:1}},{&quot;breakpoint&quot;:767,&quot;settings&quot;:{&quot;slidesToShow&quot;:1}}]}\" data-images=\"[{&quot;url&quot;:&quot;https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-00.jpg&quot;,&quot;alt&quot;:&quot;&quot;,&quot;id&quot;:0,&quot;imageId&quot;:2629,&quot;caption&quot;:&quot;&quot;,&quot;title&quot;:&quot;Slider 1&quot;,&quot;subtitle&quot;:&quot;Essential Blocks Slider Subtitle&quot;,&quot;showButton&quot;:true,&quot;buttonText&quot;:&quot;See More&quot;,&quot;buttonUrl&quot;:&quot;&quot;,&quot;openNewTab&quot;:false,&quot;isValidUrl&quot;:true,&quot;showSecondButton&quot;:false,&quot;secondButtonText&quot;:&quot;See More&quot;,&quot;secondButtonUrl&quot;:&quot;&quot;,&quot;secondButtonOpenNewTab&quot;:false},{&quot;url&quot;:&quot;https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-01.jpg&quot;,&quot;alt&quot;:&quot;&quot;,&quot;id&quot;:1,&quot;imageId&quot;:2631,&quot;caption&quot;:&quot;&quot;,&quot;title&quot;:&quot;Slider 2&quot;,&quot;subtitle&quot;:&quot;Essential Blocks Slider Subtitle&quot;,&quot;showButton&quot;:true,&quot;buttonText&quot;:&quot;See More&quot;,&quot;buttonUrl&quot;:&quot;&quot;,&quot;openNewTab&quot;:false,&quot;isValidUrl&quot;:true,&quot;showSecondButton&quot;:false,&quot;secondButtonText&quot;:&quot;See More&quot;,&quot;secondButtonUrl&quot;:&quot;&quot;,&quot;secondButtonOpenNewTab&quot;:false},{&quot;url&quot;:&quot;https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-02.jpg&quot;,&quot;alt&quot;:&quot;&quot;,&quot;id&quot;:2,&quot;imageId&quot;:2633,&quot;caption&quot;:&quot;&quot;,&quot;title&quot;:&quot;Slider 3&quot;,&quot;subtitle&quot;:&quot;Essential Blocks Slider Subtitle&quot;,&quot;showButton&quot;:true,&quot;buttonText&quot;:&quot;See More&quot;,&quot;buttonUrl&quot;:&quot;&quot;,&quot;openNewTab&quot;:false,&quot;isValidUrl&quot;:true,&quot;showSecondButton&quot;:false,&quot;secondButtonText&quot;:&quot;See More&quot;,&quot;secondButtonUrl&quot;:&quot;&quot;,&quot;secondButtonOpenNewTab&quot;:false},{&quot;url&quot;:&quot;https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-03.jpg&quot;,&quot;alt&quot;:&quot;&quot;,&quot;id&quot;:3,&quot;imageId&quot;:2635,&quot;caption&quot;:&quot;&quot;,&quot;title&quot;:&quot;Slider 4&quot;,&quot;subtitle&quot;:&quot;Essential Blocks Slider Subtitle&quot;,&quot;showButton&quot;:true,&quot;buttonText&quot;:&quot;See More&quot;,&quot;buttonUrl&quot;:&quot;&quot;,&quot;openNewTab&quot;:false,&quot;isValidUrl&quot;:true,&quot;showSecondButton&quot;:false,&quot;secondButtonText&quot;:&quot;See More&quot;,&quot;secondButtonUrl&quot;:&quot;&quot;,&quot;secondButtonOpenNewTab&quot;:false},{&quot;url&quot;:&quot;https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-04.jpg&quot;,&quot;alt&quot;:&quot;&quot;,&quot;id&quot;:4,&quot;imageId&quot;:2637,&quot;caption&quot;:&quot;&quot;,&quot;title&quot;:&quot;Slider 5&quot;,&quot;subtitle&quot;:&quot;Essential Blocks Slider Subtitle&quot;,&quot;showButton&quot;:true,&quot;buttonText&quot;:&quot;See More&quot;,&quot;buttonUrl&quot;:&quot;&quot;,&quot;openNewTab&quot;:false,&quot;isValidUrl&quot;:true,&quot;showSecondButton&quot;:false,&quot;secondButtonText&quot;:&quot;See More&quot;,&quot;secondButtonUrl&quot;:&quot;&quot;,&quot;secondButtonOpenNewTab&quot;:false},{&quot;url&quot;:&quot;https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-05.jpg&quot;,&quot;alt&quot;:&quot;&quot;,&quot;id&quot;:5,&quot;imageId&quot;:2639,&quot;caption&quot;:&quot;&quot;,&quot;title&quot;:&quot;Slider 6&quot;,&quot;subtitle&quot;:&quot;Essential Blocks Slider Subtitle&quot;,&quot;showButton&quot;:true,&quot;buttonText&quot;:&quot;See More&quot;,&quot;buttonUrl&quot;:&quot;&quot;,&quot;openNewTab&quot;:false,&quot;isValidUrl&quot;:true,&quot;showSecondButton&quot;:false,&quot;secondButtonText&quot;:&quot;See More&quot;,&quot;secondButtonUrl&quot;:&quot;&quot;,&quot;secondButtonOpenNewTab&quot;:false},{&quot;url&quot;:&quot;https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-06.jpg&quot;,&quot;alt&quot;:&quot;&quot;,&quot;id&quot;:6,&quot;imageId&quot;:2641,&quot;caption&quot;:&quot;&quot;,&quot;title&quot;:&quot;Slider 7&quot;,&quot;subtitle&quot;:&quot;Essential Blocks Slider Subtitle&quot;,&quot;showButton&quot;:true,&quot;buttonText&quot;:&quot;See More&quot;,&quot;buttonUrl&quot;:&quot;&quot;,&quot;openNewTab&quot;:false,&quot;isValidUrl&quot;:true,&quot;showSecondButton&quot;:false,&quot;secondButtonText&quot;:&quot;See More&quot;,&quot;secondButtonUrl&quot;:&quot;&quot;,&quot;secondButtonOpenNewTab&quot;:false}]\" data-slidercontenttype=\"content-1\" data-slidertype=\"image\" data-textalign=\"left\" data-arrownexticon=\"fas fa-chevron-right\" data-arrowprevicon=\"fas fa-chevron-left\" data-titletag=\"h2\" data-contenttag=\"p\"><div class=\"eb-slider-type-image\"><div class=\"eb-slider-item content-1\"><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-00.jpg\"\/><\/div><div class=\"eb-slider-item content-1\"><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-01.jpg\"\/><\/div><div class=\"eb-slider-item content-1\"><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-02.jpg\"\/><\/div><div class=\"eb-slider-item content-1\"><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-03.jpg\"\/><\/div><div class=\"eb-slider-item content-1\"><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-04.jpg\"\/><\/div><div class=\"eb-slider-item content-1\"><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-05.jpg\"\/><\/div><div class=\"eb-slider-item content-1\"><img decoding=\"async\" class=\"eb-slider-image\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/03\/2024-por-las-ramas-Teresa-Magrane-06.jpg\"\/><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider has-text-align-center stk-block stk-315f953\" data-block-id=\"315f953\"><style>.stk-315f953{align-items:center !important;margin-top:50px !important;margin-bottom:50px !important;display:flex !important}.stk-315f953 hr.stk-block-divider__hr{background:var(--theme-palette-color-4,#000000) !important;height:1px !important;width:100% !important}<\/style><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n<div class=\"root-eb-post-carousel-jndxj wp-block-essential-blocks-post-carousel\">\n    <div class=\"eb-parent-wrapper eb-parent-eb-post-carousel-jndxj \">\n        <div class=\"eb-post-carousel-jndxj style-2 slick-arrows arrow-none dot-style-1 eb-post-carousel-wrapper\"\n            data-id=\"eb-post-carousel-jndxj\"\n            data-querydata=\"a:14:{s:6:&quot;source&quot;;s:4:&quot;post&quot;;s:11:&quot;sourceIndex&quot;;i:0;s:9:&quot;rest_base&quot;;s:5:&quot;posts&quot;;s:14:&quot;rest_namespace&quot;;s:5:&quot;wp\/v2&quot;;s:6:&quot;author&quot;;s:0:&quot;&quot;;s:10:&quot;taxonomies&quot;;a:1:{s:8:&quot;category&quot;;a:5:{s:4:&quot;name&quot;;s:11:&quot;Categor\u00edas&quot;;s:9:&quot;rest_base&quot;;s:10:&quot;categories&quot;;s:14:&quot;rest_namespace&quot;;s:5:&quot;wp\/v2&quot;;s:4:&quot;slug&quot;;s:8:&quot;category&quot;;s:5:&quot;value&quot;;s:44:&quot;[{&quot;value&quot;:21,&quot;label&quot;:&quot;Muestras anteriores&quot;}]&quot;;}}s:8:&quot;per_page&quot;;s:2:&quot;40&quot;;s:6:&quot;offset&quot;;s:1:&quot;0&quot;;s:7:&quot;orderby&quot;;s:4:&quot;date&quot;;s:5:&quot;order&quot;;s:3:&quot;asc&quot;;s:7:&quot;include&quot;;s:0:&quot;&quot;;s:7:&quot;exclude&quot;;s:0:&quot;&quot;;s:15:&quot;exclude_current&quot;;b:1;s:26:&quot;exclude_password_protected&quot;;b:0;}\"\n            data-slidersettings=\"{&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;autoplaySpeed&quot;:2000,&quot;speed&quot;:500,&quot;adaptiveHeight&quot;:false,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:true,&quot;slideToShowRange&quot;:2,&quot;leftArrowIcon&quot;:&quot;fas fa-chevron-left&quot;,&quot;rightArrowIcon&quot;:&quot;fas fa-chevron-right&quot;,&quot;addIcon&quot;:false,&quot;showFallbackImg&quot;:false,&quot;fallbackImgUrl&quot;:&quot;&quot;,&quot;isRTLEnable&quot;:false,&quot;TABslideToShowRange&quot;:2,&quot;MOBslideToShowRange&quot;:1}\"\n            data-attributes=\"{&quot;preset&quot;:&quot;style-2&quot;,&quot;showThumbnail&quot;:false,&quot;showTitle&quot;:true,&quot;titleLength&quot;:&quot;10&quot;,&quot;titleTag&quot;:&quot;h4&quot;,&quot;showContent&quot;:false,&quot;contentLength&quot;:20,&quot;expansionIndicator&quot;:&quot;...&quot;,&quot;showReadMore&quot;:false,&quot;readmoreText&quot;:&quot;Read More&quot;,&quot;showMeta&quot;:false,&quot;headerMeta&quot;:&quot;[{\\&quot;value\\&quot;:\\&quot;date\\&quot;,\\&quot;label\\&quot;:\\&quot;Published Date\\&quot;}]&quot;,&quot;footerMeta&quot;:&quot;[{\\&quot;value\\&quot;:\\&quot;avatar\\&quot;,\\&quot;label\\&quot;:\\&quot;Author Avatar\\&quot;},{\\&quot;value\\&quot;:\\&quot;author\\&quot;,\\&quot;label\\&quot;:\\&quot;Author Name\\&quot;}]&quot;,&quot;authorPrefix&quot;:&quot;by&quot;,&quot;datePrefix&quot;:&quot;on&quot;,&quot;showBlockContent&quot;:true,&quot;showFeaturedPost&quot;:false,&quot;featuredPostId&quot;:&quot;&quot;,&quot;showFeaturedPostTitle&quot;:true,&quot;showFeaturedPostContent&quot;:false,&quot;showFeaturedPostMeta&quot;:true,&quot;showFeaturedHeaderMeta&quot;:true,&quot;showFeaturedFooterMeta&quot;:true,&quot;featuredMetaItems&quot;:&quot;{}&quot;,&quot;featuredExcerptLength&quot;:10,&quot;leftArrowIcon&quot;:&quot;fas fa-chevron-left&quot;,&quot;rightArrowIcon&quot;:&quot;fas fa-chevron-right&quot;,&quot;showFallbackImg&quot;:false,&quot;isRTLEnable&quot;:false}\">\n\n            <div class=\"eb-post-carousel init-eb-post-carousel-jndxj\"\n                data-id=\"eb-post-carousel-jndxj\">\n                <article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"5666\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/otto-di-rosa-en\/\" title=\"ottodirosa\">OTTO di rosa<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"5509\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/fernando-maza-la-construccion-de-la-pintura\/\" title=\"fernandomazatheconstructionofpainting\">Fernando Maza | The Construction of Painting<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"5420\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/ludi-en\/\" title=\"ludi\">Ludi<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"5272\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/entre-lo-que-se-ve-y-se-adivina-en\/\" title=\"betweenwhatisseenandwhatisguessed\">Between what is seen and what is guessed<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"4926\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/fabio-miniotti-late-bajo-la-piel-en\/\" title=\"fabiominiottiitpulsesbeneaththeskin\">Fabio Miniotti, It pulses beneath the skin<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"4775\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/huellas-compartidas-homenaje-a-daniel-callori-en\/\" title=\"huellascompartidashomenajeadanielcallori\">Huellas compartidas, homenaje a Daniel Callori<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"4146\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/alec-franco-temporada-ilogica-en\/\" title=\"alecfrancoillogicalseason\">Alec Franco, Illogical Season<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3891\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/fernando-maza-muestra-en\/\" title=\"fernandomaza\">Fernando Maza<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3744\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/structures-en\/\" title=\"structures\">Structures<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3559\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/oculto-a-simple-vista-en\/\" title=\"ocultoasimplevista\">Oculto a simple vista<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3038\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/otro-cielo-en\/\" title=\"manezorraqunotrocielo\">Mane Zorraqu\u00edn, Otro cielo<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3046\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/grupo-charco-cadaver-exquisito-en\/\" title=\"grupocharcocadverexquisito\">Grupo CHARCO, Cad\u00e1ver exquisito<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3052\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/rebeca-mendoza-el-placer-de-lo-imperceptible-en\/\" title=\"rebecamendozaelplacerdeloimperceptible\">Rebeca Mendoza, El placer de lo imperceptible<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3071\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/papel-protagonico-cuando-los-medios-son-los-fines-en\/\" title=\"papelprotagnico-cuandolosmediossonlosfines\">Papel protag\u00f3nico &#8211; Cuando los medios son los fines<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3087\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/daniel-prieto-limites-aparentes-en\/\" title=\"danielprietolmitesaparentes\">Daniel Prieto, L\u00edmites aparentes<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3094\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/claudio-larrea-portenos-en\/\" title=\"claudiolarreaporteos\">Claudio Larrea, Porte\u00f1os<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3104\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/ana-rapela-confluencia-en\/\" title=\"anarapelaconfluencia\">Ana Rapela, Confluencia<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3111\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/flavia-martini-roma-en\/\" title=\"flaviamartiniroma\">Flavia Martini, Roma<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3122\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/ackerman-stupia-videla-3x2x4-en\/\" title=\"ackermanstupavidela3x2x4\">Ackerman \/ Stup\u00eda \/ Videla, 3x2x4<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3128\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/antonia-guzman-fortalezas-en\/\" title=\"antoniaguzmnfortalezas\">Antonia Guzm\u00e1n, Fortalezas<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3135\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/alec-franco-el-color-no-esta-en-las-cosas-en\/\" title=\"alecfrancoelcolornoestenlascosas\">Alec Franco, El color no est\u00e1 en las cosas<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3142\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/mariela-marcus-celebracion-en\/\" title=\"marielamarcuscelebracin\">Mariela Marcus, Celebraci\u00f3n<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3148\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/summer-show-en\/\" title=\"summershow\">Summer Show<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3154\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/teresa-magrane-piedra-papel-y-tijera-en\/\" title=\"teresamagranepiedrapapelytijera\">Teresa Magrane, Piedra, papel y tijera<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3161\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/rebeca-mendoza-miradas-en\/\" title=\"rebecamendozamiradas\">Rebeca Mendoza, Miradas<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3168\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/marisa-gill-stillnes-en\/\" title=\"marisagillstillnes\">Marisa Gill, Stillnes<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3174\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/canzio-dardalla-miniotti-torcello-4-elementos-en\/\" title=\"canziodardallaminiottitorcello4elementos\">Canzio \/ Dardalla \/ Miniotti \/ Torcello, 4 Elementos<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3181\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/silvina-resnik-intimidad-de-los-parques-en\/\" title=\"silvinaresnikintimidaddelosparques\">Silvina Resnik, Intimidad de los parques<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3188\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/flavia-martini-jardines-imaginarios-en\/\" title=\"flaviamartinijardinesimaginarios\">Flavia Martini, Jardines imaginarios<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3193\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/daniel-prieto-danza-homenaje-a-matisse-en\/\" title=\"danielprietodanzahomenajeamatisse\">Daniel Prieto \/ Danza, homenaje a Matisse<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3200\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/florencia-gechter-dos-caras-en\/\" title=\"florenciagechterdoscaras\">Florencia Gechter, Dos Caras<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3207\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/martin-la-rosa-la-cita-en\/\" title=\"martnlarosalacita\">Mart\u00edn La Rosa, La Cita<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3212\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/mane-zorraquin-terra-en\/\" title=\"manezorraqunterra\">Mane Zorraqu\u00edn, Terra<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3218\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/hernan-cedola-algunos-retratos-y-una-naturaleza-muerta-en\/\" title=\"hernncdolaalgunosretratosyunanaturalezamuerta\">Hern\u00e1n C\u00e9dola, Algunos retratos y una naturaleza muerta<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3225\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/antonia-guzman-levitar-en\/\" title=\"antoniaguzmnlevitar\">Antonia Guzm\u00e1n, Levitar<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3231\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/ana-rapela-des-plegando-en\/\" title=\"anarapeladesplegando\">Ana Rapela, Des.plegando<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3238\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/manuel-larralde-caracter-profetico-en\/\" title=\"manuellarraldecarcterproftico\">Manuel Larralde, Car\u00e1cter Prof\u00e9tico<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3245\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/daniel-ackerman-fotografismos-en\/\" title=\"danielackermanfotografismos\">Daniel Ackerman, Fotografismos<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3252\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/chevrin-gill-stupia-caprichos-y-misterios-en\/\" title=\"chervingillstupacaprichosymisterios\">Chervin \/ Gill \/ Stup\u00eda, Caprichos y Misterios<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3260\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/monica-canzio-materia-sensible-en\/\" title=\"mnicacanziomateriasensible\">M\u00f3nica Canzio, Materia Sensible<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article>            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider has-text-align-center stk-block stk-phrc5dt\" data-block-id=\"phrc5dt\"><style>.stk-phrc5dt{align-items:center !important;margin-top:50px !important;margin-bottom:50px !important;display:flex !important}.stk-phrc5dt hr.stk-block-divider__hr{background:var(--theme-palette-color-4,#000000) !important;height:1px !important;width:100% !important}<\/style><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<div class=\"wp-block-stackable-columns alignwide stk-block-columns stk-block stk-7e4dfa6\" data-block-id=\"7e4dfa6\"><style>.stk-7e4dfa6 {margin-bottom:30px !important;}<\/style><div class=\"stk-row stk-inner-blocks has-text-align-center stk-block-content stk-content-align stk-7e4dfa6-column alignwide\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-2ac743f\" data-v=\"4\" data-block-id=\"2ac743f\"><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-2ac743f-container stk--no-background stk--no-padding\"><div class=\"has-text-align-center stk-block-content stk-inner-blocks stk-2ac743f-inner-blocks\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/catenazapata.com\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/05\/SFenElArte-logo.svg\" alt=\"\" class=\"wp-image-3578\" style=\"width:100px\"\/><\/a><\/figure>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>March 13 to April 30, 2024<\/p>\n","protected":false},"author":1,"featured_media":2638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-2890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-previous-exhibitions"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/posts\/2890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/comments?post=2890"}],"version-history":[{"count":5,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/posts\/2890\/revisions"}],"predecessor-version":[{"id":3604,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/posts\/2890\/revisions\/3604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/media\/2638"}],"wp:attachment":[{"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/media?parent=2890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/categories?post=2890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/tags?post=2890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}