{"id":4822,"date":"2024-01-31T09:47:02","date_gmt":"2024-01-31T12:47:02","guid":{"rendered":"https:\/\/ottogaleria.com\/david-sisso\/"},"modified":"2026-03-06T21:07:13","modified_gmt":"2026-03-07T00:07:13","slug":"david-sisso-en","status":"publish","type":"post","link":"https:\/\/ottogaleria.com\/en\/david-sisso-en\/","title":{"rendered":"David Sisso"},"content":{"rendered":"\n<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-7b376fe\" data-block-id=\"7b376fe\"><style>.stk-7b376fe {margin-top:40px !important;}.stk-7b376fe-column{max-width:90% !important;min-width:auto !important;--stk-columns-spacing:0px !important;--stk-column-gap:60px !important;}@media screen and (max-width:689px){.stk-7b376fe-column{--stk-column-gap:0px !important;row-gap:30px !important;}}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-7b376fe-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-92d9cd7\" data-v=\"4\" data-block-id=\"92d9cd7\"><style>.stk-92d9cd7-inner-blocks{align-items:center !important;}@media screen and (min-width:690px){.stk-92d9cd7 {flex:var(--stk-flex-grow, 1) 1 calc(20% - var(--stk-column-gap, 0px) * 1 \/ 2 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-92d9cd7-container stk--no-background stk--no-padding\"><div class=\"has-text-align-center stk--column-flex stk-block-content stk-inner-blocks stk-92d9cd7-inner-blocks\">\n<div class=\"wp-block-stackable-image stk-block-image has-text-align-center stk-block stk-dfc1d71\" data-block-id=\"dfc1d71\"><style>.stk-dfc1d71 {margin-bottom:15px !important;}.stk-dfc1d71 .stk-img-wrapper{width:160px !important;height:160px !important;}.stk-dfc1d71 .stk-img-wrapper img{border-radius:100px !important;}<\/style><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img loading=\"lazy\" decoding=\"async\" class=\"stk-img wp-image-4791\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-retrato-g.jpg\" width=\"879\" height=\"879\" srcset=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-retrato-g.jpg 879w, https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-retrato-g-300x300.jpg 300w, https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-retrato-g-150x150.jpg 150w, https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-retrato-g-768x768.jpg 768w\" sizes=\"auto, (max-width: 879px) 100vw, 879px\" \/><\/span><\/figure><\/div>\n\n\n\n<div class=\"wp-block-stackable-button-group aligncenter stk-block-button-group stk-block stk-4d02304\" data-block-id=\"4d02304\"><div class=\"stk-row stk-inner-blocks has-text-align-center stk-block-content stk-button-group\">\n<div class=\"wp-block-stackable-icon-button stk-block-icon-button stk-block stk-7f6355c is-style-plain\" data-block-id=\"7f6355c\"><style>.stk-7f6355c .stk-button{padding-top:5px !important;padding-right:5px !important;padding-bottom:5px !important;padding-left:5px !important;background:transparent !important;}.stk-7f6355c .stk-button:hover{background:transparent !important;opacity:1 !important;}:where(.stk-hover-parent:hover,  .stk-hover-parent.stk--is-hovered) .stk-7f6355c .stk-button:after{background:transparent !important;opacity:1 !important;}.stk-7f6355c .stk-button:before{border-color:var(--theme-palette-color-4, #000000) !important;}.stk-7f6355c .stk-button .stk--inner-svg svg:last-child{height:18px !important;width:18px !important;}.stk-7f6355c .stk-button .stk--inner-svg svg:last-child, .stk-7f6355c .stk-button .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:var(--theme-palette-color-4, #000000) !important;}<\/style><a class=\"stk-link stk-button stk--hover-effect-darken\" href=\"mailto:otto@ottogaleria.com?subject=Consulta%20sobre%20David Sisso&amp;body=Hola,%20quiero%20informaci\u00f3n.%20Gracias\" title=\"Consulta\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M64 112c-8.8 0-16 7.2-16 16v22.1L220.5 291.7c20.7 17 50.4 17 71.1 0L464 150.1V128c0-8.8-7.2-16-16-16H64zM48 212.2V384c0 8.8 7.2 16 16 16H448c8.8 0 16-7.2 16-16V212.2L322 328.8c-38.4 31.5-93.7 31.5-132 0L48 212.2zM0 128C0 92.7 28.7 64 64 64H448c35.3 0 64 28.7 64 64V384c0 35.3-28.7 64-64 64H64c-35.3 0-64-28.7-64-64V128z\"\/><\/svg><\/div><\/span><\/a><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon-button stk-block-icon-button stk-block stk-dacf5ce is-style-plain\" data-block-id=\"dacf5ce\"><style>.stk-dacf5ce .stk-button{padding-top:5px !important;padding-right:5px !important;padding-bottom:5px !important;padding-left:5px !important;background:transparent !important;}.stk-dacf5ce .stk-button:hover{background:transparent !important;opacity:1 !important;}:where(.stk-hover-parent:hover,  .stk-hover-parent.stk--is-hovered) .stk-dacf5ce .stk-button:after{background:transparent !important;opacity:1 !important;}.stk-dacf5ce .stk-button .stk--inner-svg svg:last-child{height:18px !important;width:18px !important;}.stk-dacf5ce .stk-button .stk--inner-svg svg:last-child, .stk-dacf5ce .stk-button .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:var(--theme-palette-color-4, #000000) !important;}<\/style><a class=\"stk-link stk-button stk--hover-effect-darken\" href=\"https:\/\/ottogaleria.com\/en\/press\/\" title=\"Prensa\"><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M168 80c-13.3 0-24 10.7-24 24V408c0 8.4-1.4 16.5-4.1 24H440c13.3 0 24-10.7 24-24V104c0-13.3-10.7-24-24-24H168zM72 480c-39.8 0-72-32.2-72-72V112C0 98.7 10.7 88 24 88s24 10.7 24 24V408c0 13.3 10.7 24 24 24s24-10.7 24-24V104c0-39.8 32.2-72 72-72H440c39.8 0 72 32.2 72 72V408c0 39.8-32.2 72-72 72H72zM176 136c0-13.3 10.7-24 24-24h96c13.3 0 24 10.7 24 24v80c0 13.3-10.7 24-24 24H200c-13.3 0-24-10.7-24-24V136zm200-24h32c13.3 0 24 10.7 24 24s-10.7 24-24 24H376c-13.3 0-24-10.7-24-24s10.7-24 24-24zm0 80h32c13.3 0 24 10.7 24 24s-10.7 24-24 24H376c-13.3 0-24-10.7-24-24s10.7-24 24-24zM200 272H408c13.3 0 24 10.7 24 24s-10.7 24-24 24H200c-13.3 0-24-10.7-24-24s10.7-24 24-24zm0 80H408c13.3 0 24 10.7 24 24s-10.7 24-24 24H200c-13.3 0-24-10.7-24-24s10.7-24 24-24z\"\/><\/svg><\/div><\/span><\/a><\/div>\n\n\n\n<div class=\"wp-block-stackable-icon-button stk-block-icon-button stk-block stk-a8c8fbb is-style-plain\" data-block-id=\"a8c8fbb\"><style>.stk-a8c8fbb .stk-button{padding-top:5px !important;padding-right:5px !important;padding-bottom:5px !important;padding-left:5px !important;background:transparent !important;}.stk-a8c8fbb .stk-button:hover{background:transparent !important;opacity:1 !important;}:where(.stk-hover-parent:hover,  .stk-hover-parent.stk--is-hovered) .stk-a8c8fbb .stk-button:after{background:transparent !important;opacity:1 !important;}.stk-a8c8fbb .stk-button .stk--inner-svg svg:last-child{height:18px !important;width:18px !important;}.stk-a8c8fbb .stk-button .stk--inner-svg svg:last-child, .stk-a8c8fbb .stk-button .stk--inner-svg svg:last-child :is(g, path, rect, polygon, ellipse){fill:var(--theme-palette-color-4, #000000) !important;}<\/style><a class=\"stk-link stk-button stk--hover-effect-darken\" href=\"https:\/\/www.artsy.net\/otto-galeria\/artist\/david-sisso\" title=\"Tienda online\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"stk--svg-wrapper\"><div class=\"stk--inner-svg\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\" aria-hidden=\"true\" width=\"32\" height=\"32\"><path d=\"M0 24C0 10.7 10.7 0 24 0H69.5c22 0 41.5 12.8 50.6 32h411c26.3 0 45.5 25 38.6 50.4l-41 152.3c-8.5 31.4-37 53.3-69.5 53.3H170.7l5.4 28.5c2.2 11.3 12.1 19.5 23.6 19.5H488c13.3 0 24 10.7 24 24s-10.7 24-24 24H199.7c-34.6 0-64.3-24.6-70.7-58.5L77.4 54.5c-.7-3.8-4-6.5-7.9-6.5H24C10.7 48 0 37.3 0 24zM128 464a48 48 0 1 1 96 0 48 48 0 1 1 -96 0zm336-48a48 48 0 1 1 0 96 48 48 0 1 1 0-96z\"\/><\/svg><\/div><\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-e5cd9a1\" data-v=\"4\" data-block-id=\"e5cd9a1\"><style>@media screen and (min-width:690px){.stk-e5cd9a1 {flex:var(--stk-flex-grow, 1) 1 calc(80% - var(--stk-column-gap, 0px) * 1 \/ 2 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-e5cd9a1-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-e5cd9a1-inner-blocks\">\n<p>David Sisso is a photographer and visual artist born in San Luis in 1968, and porte\u00f1o by choice since 1993. After studying Communication Sciences, he worked as an editorial photographer for remarkable local and international publications.<\/p>\n\n\n\n<p>For 7 years he was Editor of Photography for Rolling Stone magazine and author of its most memorable productions. As an advertising photographer, he worked with the main brands and local agencies. His personal work began to be exhibited in 2010 in galleries and art fairs. In 2013 he won the Repsol Lima Photo award. Soon after in 2017, Editorial Planeta released his photography book &#8220;Tierra Vac\u00eda&#8221; a project that is shown the same year at the Fototeca Latinoamericana in Buenos Aires.<\/p>\n\n\n\n<p>Since 2018, he has been working on mixed-media projects that explore the languages \u200b\u200bof other disciplines, such as painting, video, and drawing.<\/p>\n\n\n\n<p>He currently lives and works in Buenos Aires.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider has-text-align-center stk-block stk-315f953\" data-block-id=\"315f953\"><style>.stk-315f953{align-items:center !important;margin-top:50px !important;margin-bottom:50px !important;display:flex !important}.stk-315f953 hr.stk-block-divider__hr{background:var(--theme-palette-color-4,#000000) !important;height:1px !important;width:100% !important}<\/style><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-image-gallery  root-eb-image-gallery-t70o7\"><div class=\"eb-parent-wrapper eb-parent-eb-image-gallery-t70o7 \"><div class=\"eb-gallery-img-wrapper eb-image-gallery-t70o7 default v2 masonry null enable-isotope   overlay-bottom caption-style-0 caption-on-hover \" data-id=\"eb-image-gallery-t70o7\" data-searchfilter=\"false\"><div class=\"grid-sizer\"><\/div><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Historias-Verdaderas-006-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Historias-Verdaderas-006-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" image-index=\"0\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">Historias Verdaderas #001 series, mixed media on paper, 67 x 56 cm, 2026, monoprint<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Historias-Verdaderas-004-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Historias-Verdaderas-004-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" image-index=\"1\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">Historias Verdaderas #001 series, mixed media on paper, 67 x 56 cm, 2026, monoprint<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Historias-Verdaderas-003-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Historias-Verdaderas-003-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" image-index=\"2\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">Historias Verdaderas #001 series, mixed media on paper, 67 x 56 cm, 2026, monoprint<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Historias-Verdaderas-001-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Historias-Verdaderas-001-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" image-index=\"3\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">Historias Verdaderas #001 series, mixed media on paper, 67 x 56 cm, 2026, monoprint<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Dioramas-001-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Serie-Dioramas-001-Tecnica-mixta-sobre-papel-67x56cm-2026-Monocopia.jpg\" image-index=\"4\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">Dioramas #001 series, mixed media on paper, 67 x 56 cm, 2026, monoprint<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Sisso-DPP017_2024.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Sisso-DPP017_2024.jpg\" image-index=\"5\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">DPP #017, 2024<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Sisso-Serie-Aproximaciones-ST-fotografia-de-capturas-multiples-144x100cm-2019.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Sisso-Serie-Aproximaciones-ST-fotografia-de-capturas-multiples-144x100cm-2019.jpg\" image-index=\"6\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">Serie Aproximaciones, Untitled, multiple capture photography, 144 x 100 cm, 2019<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Sisso-GGPP012_2025.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2024\/01\/Sisso-GGPP012_2025.jpg\" image-index=\"7\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">GGPP #012, 2025<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-02.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-02.jpg\" image-index=\"8\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">DPP #008, 2024, vector layout, printed on penplotter, 70 \u00d7 50 cm<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-08.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-08.jpg\" image-index=\"9\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">ST, #013, De la serie Deriva, 2020, mixed media, gicl\u00e9e print, impresi\u00f3n gicl\u00e9e, 137 \u00d7 104 cm<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-05.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-05.jpg\" image-index=\"10\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">DPP #004, 2024, vector layout, printed on penplotter, 70 \u00d7 50 cm<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-04.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-04.jpg\" image-index=\"11\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">DPP #007, 2024, vector layout, printed on penplotter, 70 \u00d7 50 cm<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-10.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-10.jpg\" image-index=\"12\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">ST, #002, De la serie Deriva, 2020, 10. ST, #002, De la serie Deriva, 2020, mixed media, gicl\u00e9e print, 137 \u00d7 104 cm<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-03.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-03.jpg\" image-index=\"13\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">DPP #013, 2024, vector layout, printed on penplotter, 70 \u00d7 50 cm<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-01.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-01.jpg\" image-index=\"14\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">DPP #001, 2024, vector layout, printed on penplotter, 70 \u00d7 50 cm<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-09.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-09.jpg\" image-index=\"15\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">ST, #001, De la serie Deriva, 2020, mixed media, gicl\u00e9e print, 137 \u00d7 104 cm<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-07.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-07.jpg\" image-index=\"16\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">DPP #015, 2024, vector layout, printed on penplotter, 70 \u00d7 50 cm<\/span><\/span><\/span><\/a><a href=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-06.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content  eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/ottogaleria.com\/sitio\/wp-content\/uploads\/2025\/03\/David-Sisso-06.jpg\" image-index=\"17\" alt=\"\"\/><span class=\"eb-img-gallery-content center bottom\"><span class=\"eb-gallery-img-caption\">DPP #010, 2024, vector layout, printed on penplotter, 70 \u00d7 50 cm<\/span><\/span><\/span><\/a><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-divider stk-block-divider has-text-align-center stk-block stk-x08gch6\" data-block-id=\"x08gch6\"><style>.stk-x08gch6{align-items:center !important;margin-top:50px !important;margin-bottom:50px !important;display:flex !important}.stk-x08gch6 hr.stk-block-divider__hr{background:var(--theme-palette-color-4,#000000) !important;height:1px !important;width:100% !important}<\/style><hr class=\"stk-block-divider__hr\"\/><\/div>\n\n\n<div class=\"root-eb-post-carousel-yykhm wp-block-essential-blocks-post-carousel\">\n    <div class=\"eb-parent-wrapper eb-parent-eb-post-carousel-yykhm \">\n        <div class=\"eb-post-carousel-yykhm style-2 slick-arrows arrow-none dot-style-1 eb-post-carousel-wrapper\"\n            data-id=\"eb-post-carousel-yykhm\"\n            data-querydata=\"a:14:{s:6:&quot;source&quot;;s:4:&quot;post&quot;;s:11:&quot;sourceIndex&quot;;i:0;s:9:&quot;rest_base&quot;;s:5:&quot;posts&quot;;s:14:&quot;rest_namespace&quot;;s:5:&quot;wp\/v2&quot;;s:6:&quot;author&quot;;s:0:&quot;&quot;;s:10:&quot;taxonomies&quot;;a:1:{s:8:&quot;category&quot;;a:5:{s:4:&quot;name&quot;;s:11:&quot;Categor\u00edas&quot;;s:9:&quot;rest_base&quot;;s:10:&quot;categories&quot;;s:14:&quot;rest_namespace&quot;;s:5:&quot;wp\/v2&quot;;s:4:&quot;slug&quot;;s:8:&quot;category&quot;;s:5:&quot;value&quot;;s:46:&quot;[{&quot;value&quot;:8,&quot;label&quot;:&quot;Artistas de la galeria&quot;}]&quot;;}}s:8:&quot;per_page&quot;;s:2:&quot;30&quot;;s:6:&quot;offset&quot;;s:1:&quot;0&quot;;s:7:&quot;orderby&quot;;s:4:&quot;date&quot;;s:5:&quot;order&quot;;s:3:&quot;asc&quot;;s:7:&quot;include&quot;;s:0:&quot;&quot;;s:7:&quot;exclude&quot;;s:0:&quot;&quot;;s:15:&quot;exclude_current&quot;;b:1;s:26:&quot;exclude_password_protected&quot;;b:0;}\"\n            data-slidersettings=\"{&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;autoplaySpeed&quot;:2000,&quot;speed&quot;:500,&quot;adaptiveHeight&quot;:false,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:true,&quot;slideToShowRange&quot;:5,&quot;leftArrowIcon&quot;:&quot;fas fa-chevron-left&quot;,&quot;rightArrowIcon&quot;:&quot;fas fa-chevron-right&quot;,&quot;addIcon&quot;:false,&quot;showFallbackImg&quot;:false,&quot;fallbackImgUrl&quot;:&quot;&quot;,&quot;isRTLEnable&quot;:false,&quot;TABslideToShowRange&quot;:2,&quot;MOBslideToShowRange&quot;:1}\"\n            data-attributes=\"{&quot;preset&quot;:&quot;style-2&quot;,&quot;showThumbnail&quot;:false,&quot;showTitle&quot;:true,&quot;titleLength&quot;:&quot;10&quot;,&quot;titleTag&quot;:&quot;h4&quot;,&quot;showContent&quot;:false,&quot;contentLength&quot;:20,&quot;expansionIndicator&quot;:&quot;...&quot;,&quot;showReadMore&quot;:false,&quot;readmoreText&quot;:&quot;Read More&quot;,&quot;showMeta&quot;:false,&quot;headerMeta&quot;:&quot;[{\\&quot;value\\&quot;:\\&quot;date\\&quot;,\\&quot;label\\&quot;:\\&quot;Published Date\\&quot;}]&quot;,&quot;footerMeta&quot;:&quot;[{\\&quot;value\\&quot;:\\&quot;avatar\\&quot;,\\&quot;label\\&quot;:\\&quot;Author Avatar\\&quot;},{\\&quot;value\\&quot;:\\&quot;author\\&quot;,\\&quot;label\\&quot;:\\&quot;Author Name\\&quot;}]&quot;,&quot;authorPrefix&quot;:&quot;by&quot;,&quot;datePrefix&quot;:&quot;on&quot;,&quot;showBlockContent&quot;:true,&quot;showFeaturedPost&quot;:false,&quot;featuredPostId&quot;:&quot;&quot;,&quot;showFeaturedPostTitle&quot;:true,&quot;showFeaturedPostContent&quot;:false,&quot;showFeaturedPostMeta&quot;:true,&quot;showFeaturedHeaderMeta&quot;:true,&quot;showFeaturedFooterMeta&quot;:true,&quot;featuredMetaItems&quot;:&quot;{}&quot;,&quot;featuredExcerptLength&quot;:10,&quot;leftArrowIcon&quot;:&quot;fas fa-chevron-left&quot;,&quot;rightArrowIcon&quot;:&quot;fas fa-chevron-right&quot;,&quot;showFallbackImg&quot;:false,&quot;isRTLEnable&quot;:false}\">\n\n            <div class=\"eb-post-carousel init-eb-post-carousel-yykhm\"\n                data-id=\"eb-post-carousel-yykhm\">\n                <article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3369\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/daniel-ackerman-en\/\" title=\"danielackerman\">Daniel Ackerman<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3410\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/carlos-arnaiz-en\/\" title=\"carlosarnaiz\">Carlos Arnaiz<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3425\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/maria-baya-en\/\" title=\"marabay\">Mar\u00eda Bay\u00e1<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"5130\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/rosario-briones-en\/\" title=\"rosariobriones\">Rosario Briones<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3430\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/daniel-callori-en\/\" title=\"danielcalloriestate\">Daniel Callori (Estate)<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3434\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/monica-canzio-en\/\" title=\"mnicacanzio\">M\u00f3nica Canzio<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3438\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/cintia-cuesta-en\/\" title=\"cintiacuesta\">Cintia Cuesta<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3442\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/alec-franco-en\/\" title=\"alecfranco\">Alec Franco<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3451\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/marisa-gill-en\/\" title=\"marisagill\">Marisa Gill<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3456\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/dafne-kleiman-en\/\" title=\"dafnekleiman\">Dafne Kleiman<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3477\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/teresa-magrane-en\/\" title=\"teresamagrane\">Teresa Magrane<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3491\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/fernando-maza-en\/\" title=\"fernandomazaestate\">Fernando Maza (Estate)<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3496\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/rebeca-mendoza-en\/\" title=\"rebecamendoza\">Rebeca Mendoza<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3501\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/fabio-miniotti-en\/\" title=\"fabiominiotti\">Fabio Miniotti<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3505\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/daniel-prieto-en\/\" title=\"danielprieto\">Daniel Prieto<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3509\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/ana-rapela-en\/\" title=\"anarapela\">Ana Rapela<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"4518\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/daniel-stroomer-en\/\" title=\"danielstroomer\">Daniel Stroomer<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3518\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/eduardo-stupia-en\/\" title=\"eduardostupa\">Eduardo Stup\u00eda<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article><article class=\"ebpg-carousel-post ebpg-post-carousel-column\" data-id=\"3525\"><div class=\"ebpg-carousel-post-holder\"><div class=\"ebpg-entry-wrapper\"><header class=\"ebpg-entry-header\">\n            <h4 class=\"ebpg-entry-title\">\n                <a class=\"ebpg-carousel-post-link\" href=\"https:\/\/ottogaleria.com\/en\/mane-zorraquin-en\/\" title=\"manezorraqun\">Mane Zorraqu\u00edn<\/a>\n            <\/h4>\n        <\/header><\/div><\/div><\/article>            <\/div>\n        <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>David Sisso is a photographer and visual artist born in San Luis in 1968, and porte\u00f1o by choice since 1993. After studying Communication Sciences, he worked as an editorial photographer for remarkable local and international publications. For 7 years he was Editor of Photography for Rolling Stone magazine and author of its most memorable productions. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-4822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gallery-artists"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/posts\/4822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/comments?post=4822"}],"version-history":[{"count":6,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/posts\/4822\/revisions"}],"predecessor-version":[{"id":6005,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/posts\/4822\/revisions\/6005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/media\/6003"}],"wp:attachment":[{"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/media?parent=4822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/categories?post=4822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ottogaleria.com\/en\/wp-json\/wp\/v2\/tags?post=4822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}